{"id":12840,"date":"2014-01-15T11:49:20","date_gmt":"2014-01-15T10:49:20","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=12840"},"modified":"2015-12-16T09:12:28","modified_gmt":"2015-12-16T08:12:28","slug":"lte-waechst-rasant-weltweit-260-lte-netze-in-betrieb","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/lte-waechst-rasant-weltweit-260-lte-netze-in-betrieb","title":{"rendered":"LTE w\u00e4chst rasant: Weltweit 260 LTE-Netze in Betrieb"},"content":{"rendered":"<p>Die Zahlen sprechen B\u00e4nde: Weltweit konnte LTE 2013 immens zulegen und damit zur am schnellsten wachsende Mobilfunktechnologie bisher werden. Auch f\u00fcr 2014 werden gro\u00dfe Schritte und wichtige Entwicklungen erwartet.<!--more--><\/p>\n<h2>LTE auf dem Vormarsch<\/h2>\n<p>Bis zum Ende 2013 haben weltweit 260 Netzbetreiber kommerzielle LTE-Dienste angeboten. Das geht aus einem aktuellen Report des Branchenverbands GSA (Global mobile Suppliers Association) hervor. In insgesamt 95 L\u00e4ndern ist LTE mittlerweile bei mindestens einem der ans\u00e4ssigen Mobilfunkanbietern verf\u00fcgbar &#8211; von den 260 Netzbetreibern sind im Jahr 2013 allein 112 neue LTE-Netze in Betrieb genommen worden. Damit ist LTE die am schnellsten wachsende Mobilfunktechnologie bisher, so die Analysten. Und der Trend wird auch 2014 weiter anhalten. In der ersten Januar-H\u00e4lfte gingen bereits drei neue LTE-Netze in zwei zus\u00e4tzlichen Nationen an den Start.<\/p>\n<h2>Zwischen Nutzung und Tests<\/h2>\n<p>Laut GSA investieren weltweit 508 Netzbetreiber in 144 Nationen in LTE-Technologie &#8211; doch nicht alle Unternehmen sind bereits soweit, um den kommerziellen Betrieb zu starten. Zum Teil sind die Unternehmen zudem auch vorrangig daran interessiert, Versuche oder Studien mit der Technologie durchzuf\u00fchren, weswegen einige der nicht-kommerziellen Netze wohl vorerst auch keine werden. Insgesamt gibt momentan rund 75 Prozent mehr kommerzielle LTE-Services, als noch vor einem Jahr. F\u00fcr 2014 erwartet der Branchenverband global den Anstieg auf 350 kommerzielle 4G-Netze, was einem rund 20 Prozent langsameren Wachstum als noch 2013 entsprechen w\u00fcrde.<\/p>\n<h2>Wichtige Trends &#8211; Die Vielfalt der Anwendungsgebiete<\/h2>\n<p>Nichtsdestotrotz blickt der Verband sehr optimistisch in das neue Jahr, denn erweiterte Anwendungsgebiete, wie <a href=\"https:\/\/www.lte-anbieter.info\/lte-advanced\/\">LTE Advanced<\/a>, werden in diesem Jahr an Bedeutung gewinnen. Auch f\u00fcr LTE Broadcast soll es ein wichtiges Jahr werden, sind sich die Experten sicher &#8211; denn <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/lte-broadcast-telstra-testet\">schon 2014<\/a> k\u00f6nnten erste kommerzielle Dienste mit TV-\u00dcbertragungen \u00fcber LTE starten. W\u00e4hrend Roaming im <a href=\"https:\/\/www.lte-anbieter.info\/3g\/\" data-internallinksmanager029f6b8e52c=\"74\" title=\"alles \u00fcber 3G und dessen Abschaltung erfahren\">3G<\/a>-Netz bereits allt\u00e4glich ist, sind f\u00fcr den Mobilfunkstandard der vierten Generation bisher kaum Vertr\u00e4ge zwischen Mobilfunkanbietern vereinbart worden. Diese L\u00fccke soll 2014 geschlossen werden. Erste <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/lte-roaming-kommt-endlich-voran\">Erfolge in der Schweiz<\/a> gibt es schon. Zudem wird auch eine zunehmende Verbreitung von Sprachendiensten mittels <a href=\"https:\/\/www.lte-anbieter.info\/volte\/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"mehr \u00fcber VoLTE (LTE-Telefonie) erfahren\">VoLTE<\/a> gerechnet. Wichtigstes Kriterium daf\u00fcr ist jedoch die Fl\u00e4chendeckende Versorgung der LTE-Netze. Entsprechende Mobiltelefone mit VoLTE-Funktion sind in den letzten Monaten vermehrt auf den Markt gekommen.<\/p>\n<h2>Ger\u00e4te &#8211; Wer kann LTE?<\/h2>\n<p>Ohne die richtigen Endger\u00e4te w\u00e4re die beste LTE-Versorgung wertlos &#8211; doch dar\u00fcber brauchen sich Endkunden mittlerweile keinerlei sorgen zu machen. Weltweit waren gegen Ende 2013 insgesamt 1240 LTE-f\u00e4hige Ger\u00e4te erh\u00e4ltlich. Den gr\u00f6\u00dften Teil machen dabei Smartphones (455 Modelle) aus, gefolgt von Routen und pers\u00f6nlichen Hotspots mit 385 erh\u00e4ltlichen Modellen. Dongles, wie USB-Sticks, machen mit 165 Modellen den dritten Platz aus, gefolgt von speziellen LTE-Modulen (102) und Tabletts (93). Notebooks (30), Femtozellen (8) und PC-Karten (1) machen einen nur unerheblichen Anteil aus. Insgesamt sind LTE-Ger\u00e4te aus der Hand von 120 Herstellern erh\u00e4ltlich.<\/p>\n<div class=\"quellenews2\">Quelle: GSA<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Die Zahlen sprechen B\u00e4nde: Weltweit konnte LTE 2013 immens zulegen und damit zur am schnellsten wachsende Mobilfunktechnologie bisher werden. Auch f\u00fcr 2014 werden gro\u00dfe Schritte und wichtige Entwicklungen erwartet.<\/p>\n","protected":false},"author":15,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":1,"footnotes":""},"categories":[66],"tags":[8,1250,37,226,42],"class_list":["post-12840","post","type-post","status-publish","format-standard","hentry","category-studien-prognosen","tag-lte","tag-lte-broadcast","tag-lte-advanced","tag-studie","tag-volte"],"views":1612,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-3l6","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/12840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=12840"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/12840\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=12840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=12840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=12840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}