{"id":13042,"date":"2014-02-26T08:58:03","date_gmt":"2014-02-26T07:58:03","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=13042"},"modified":"2023-02-22T09:57:03","modified_gmt":"2023-02-22T08:57:03","slug":"b3000-neuer-lte-router-ab-april-bei-vodafone","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/b3000-neuer-lte-router-ab-april-bei-vodafone","title":{"rendered":"B3000: Neuer LTE-Router ab April bei Vodafone"},"content":{"rendered":"<p>Bereits seit einiger Zeit gab es Ger\u00fcchte und Vermutungen, dass <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\" data-internallinksmanager029f6b8e52c=\"33\" title=\"Vodafone LTE- und 5G-Tarife zeigen\">Vodafone<\/a> und die Telekom in den kommenden Monaten die n\u00e4chste <a href=\"https:\/\/www.lte-anbieter.info\/lte-hardware\/router\/lte-router-ratgeber.php\" data-internallinksmanager029f6b8e52c=\"23\" title=\"LTE Router in der \u00dcbersicht + Ratgeber\">LTE-Router<\/a> Generation einf\u00fchren werden. Ab April f\u00fchrt Vodafone den Nachfolger des B2000 ein.<!--more--><\/p>\n<h2>B3000 \u2013 erste Eckdaten<\/h2>\n<p>Hinter dem B3000 steckt erneut ein Huawei-Router. Und zwar mit der Bezeichnung <a href=\"https:\/\/www.lte-anbieter.info\/lte-hardware\/all\/lte-router-huawei-b593s-22\">B593s-22<\/a>. Das interne LTE-Modem (von <a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/smartphone\/hisilicon-prozessoren.php\" data-internallinksmanager029f6b8e52c=\"70\" title=\"Alle Hisilicon Chips f\u00fcr 4G im Vergleich\">Hisilicon<\/a>) unterst\u00fctzt sogar LTE der Kategorie 4 (<a href=\"https:\/\/www.lte-anbieter.info\/technik\/kategorien-und-3gpp-release.php\" title=\"Was sind LTE-Kategorien und CAT4?\" target=\"_blank\" rel=\"noopener\">CAT4<\/a>). Somit k\u00f6nnen station\u00e4r Daten\u00fcbertragungsraten von bis zu 150 Mbit pro Sekunde erreicht werden. Profitieren d\u00fcrften davon allerdings nur ein sehr geringer Bruchteil der Zuhause-LTE-Kunden, da CAT4 LTE ma\u00dfgeblich in Ballungszentren ausgebaut ist bzw. ausgebaut wird. Wahrscheinlich noch dieses Jahr plant Vodafone die Abdeckung aller St\u00e4dte mit CAT4, die mindestens 100.000 Einwohner ausweisen.<\/p>\n<p>&nbsp;<\/p>\n<p>Ansonsten gibt es im Vergleich zum Vorg\u00e4nger kaum nennenswerte Unterschiede, zumindest auf dem Papier. Die R\u00fcckseite bietet 4 LAN-Ports und zwei RJ11-Buchsen f\u00fcr Telefonie per VOIP. Also etwa der Festnetzflat, die es in Verbindung mit den <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\" title=\"vergleichen\" target=\"_blank\" rel=\"noopener\">LTE-Zuhause-Tarifen von Vodafone<\/a> gibt. Des Weiteren ein USB-Anschluss und 2 SMA-Buchsen zum Anschluss spezieller <a href=\"https:\/\/www.lte-anbieter.info\/lte-hardware\/antenne.php\" data-internallinksmanager029f6b8e52c=\"25\" title=\"Ratgeber zur Wahl der besten LTE-Antenne\">LTE-Antennen<\/a>. Zudem sei der Router DLNA-f\u00e4hig. WLAN nach dem neusten AC-Standard sucht man leider beim B3000 vergebens.<\/p>\n<p>&nbsp;<\/p>\n<p>Und wie sieht es aus in Sachen 4G-Kompatibilit\u00e4t? An dieser Stelle gibt es erfreulicher Weise keine Beanstandungen. Alle in Deutschland g\u00e4ngigen B\u00e4nder werden supported, also LTE 800, 1800, 2100 und 2600. Sogar LTE auf 900 MHz beherrscht der B3000 theoretisch. <\/p>\n<h2>Verf\u00fcgbarkeit und Kosten<\/h2>\n<p>Vodafone plant, nach eigenen Angaben, den B3000 im April einzuf\u00fchren. Der Aufpreis f\u00fcr die Business-Kunden <a href=\"https:\/\/www.lte-anbieter.info\/tarife\/lte-datentarife-ratgeber.php\" data-internallinksmanager029f6b8e52c=\"6\" title=\"Datentarife vergleichen\">Datentarife<\/a> betr\u00e4gt einmalig rund 10 \u20ac. F\u00fcr Privatkunden zahlen einmalig knapp 50 Euro. Ob der Router auch ohne Neuvertrag im Shop erh\u00e4ltlich sein wird, ist noch nicht genau bekannt. Tipp: Ganz eilige k\u00f6nnen mitunter schon bei Amazon &#038; Co. f\u00fcndig werden. Wir entdeckten zwei H\u00e4ndler, die das Ger\u00e4t bereits f\u00fcr ca. 230\u20ac vertreiben. Allerdings sieht es um die Verf\u00fcgbarkeit aktuell noch recht d\u00fcrftig aus, wie es scheint. <\/p>\n<h2>Fazit<\/h2>\n<p>Der ganz gro\u00dfe Wurf ist der B3000 auf den ersten Blick sicher nicht. Viele \u00c4nderungen sind eher kosmetischer Natur und werden eine Umr\u00fcstung f\u00fcr Bestandskunden wahrscheinlich kaum rechtfertigen. Neukunden sind dagegen k\u00fcnftig etwas besser gestellt, verglichen mit der nicht immer einwandfrei funktionierenden EB904 LTE. Wie sich das neue Modell im Praxiseinsatz schl\u00e4gt, werden wir bald in einem Testbericht ermitteln.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"pic_l_cl\"><img decoding=\"async\" src=\"https:\/\/www.lte-anbieter.info\/lte-news\/wp-content\/uploads\/2014\/02\/b3000.jpg\" alt=\"Der neue B3000 von Vodafone\" class=\"fullwidth\"><\/div>\n<p>&nbsp;<\/p>\n<div class=\"quellenews2\">\nQuelle: Vodafone Pressemitteilung\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Bereits seit einiger Zeit gab es Ger\u00fcchte und Vermutungen, dass Vodafone und die Telekom in den kommenden Monaten die n\u00e4chste LTE-Router Generation einf\u00fchren werden. Ab April f\u00fchrt Vodafone den Nachfolger des B2000 ein.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":1,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[253],"tags":[1284,463,33],"class_list":["post-13042","post","type-post","status-publish","format-standard","hentry","category-vodafone-lte-anbieter","tag-b3000","tag-router","tag-vodafone"],"views":4960,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":13,"sum_votes":36},"jetpack_shortlink":"https:\/\/wp.me\/pOOxv-3om","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/13042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=13042"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/13042\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=13042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=13042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=13042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}