{"id":14367,"date":"2014-09-10T15:30:15","date_gmt":"2014-09-10T13:30:15","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=14367"},"modified":"2023-02-23T10:52:12","modified_gmt":"2023-02-23T09:52:12","slug":"apple-iphone-6-mit-volte-groesser-flacher-runder","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/apple-iphone-6-mit-volte-groesser-flacher-runder","title":{"rendered":"Apple iPhone 6 mit VoLTE: Gr\u00f6\u00dfer, flacher, runder"},"content":{"rendered":"<p>Eigentlich ist es schade, dass schon im Vorfeld der Apple-Pr\u00e4sentation die wichtigsten Details der neuen iPhones bekannt waren. So blieb der Wow-Effekt, den Steve Jobs einst ausl\u00f6sen konnte, weitestgehend aus. Konzernchef Tim Cook best\u00e4tigte praktisch, was zuvor schon durchgesickert war: Ja, das iPhone 6 wird deutlich gr\u00f6\u00dfer und ja, es kommt in den zwei Gr\u00f6\u00dfen 4,7 und 5,5 Zoll. Neu sind der <a href=\"https:\/\/www.lte-anbieter.info\/technik\/nfc.php\" data-internallinksmanager029f6b8e52c=\"14\" title=\"alles \u00fcber den NFC Standard f\u00fcr Smartphones\">NFC<\/a>-Bezahldienst Apple Pay sowie die verbesserte Telefonieoption <a href=\"https:\/\/www.lte-anbieter.info\/volte\/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"mehr \u00fcber VoLTE (LTE-Telefonie) erfahren\">VoLTE<\/a> &#8211; beides wird jedoch vorerst nur in den USA zur Verf\u00fcgung stehen. <!--more--><\/p>\n<h2>iPhone 6<\/h2>\n<p>Steve Jobs hatte einst behauptet, der Nutzer brauche kein gr\u00f6\u00dferes iPhone. Nun hat Apple (endlich) die Realit\u00e4ten eingesehen und reagiert auf den gro\u00dfen Erfolg der Konkurrenz mit gro\u00dfen Displays. Das neue Standardmodell iPhone 6 ist wie erwartet 4,7 Zoll gro\u00df und damit satte 0,7 Zoll gr\u00f6\u00dfer als der Vorg\u00e4nger iPhone 5. Apple bleibt damit aber immer noch unter der direkten Konkurrenz von Samsung, HTC oder Sony, deren Flaggschiffe bei 5 Zoll beginnen. Etwas entt\u00e4uschend &#8211; zumindest von den nackten Zahlen her &#8211; und nicht mehr up to date, ist die Aufl\u00f6sung des Retina-Bildschirms. Dieser weist mit 750 x 1.334 Pixeln die gleiche Pixeldichte von 326 ppi aufweist, wie das iPhone 5. Fortschritt also in Punkto Display leider Fehlanzeige. Standard sind hier mittlerweile Werte deutlich \u00fcber 400, die sich auch beim Zoomen von Texten und Bildern auszahlen. <\/p>\n<h2>Neues Design und Verbesserungen bei LTE<\/h2>\n<div class=\"pic_r\"><img decoding=\"async\" src=\"https:\/\/www.lte-anbieter.info\/lte-news\/wp-content\/uploads\/2014\/09\/iphone6-1.jpg\" alt=\"iPhone6\" width=\"290\"><\/div>\n<p>Ein Kaufkriterium ist sicherlich das neue Design des iPhone 6: Das Display wird nahtlos von einem glatten Alugeh\u00e4use umfasst, dessen Ecken und Kanten deutlich abgerundeter sind als zuvor. Das Smartphone ist nat\u00fcrlich l\u00e4nger und breiter als die Vorg\u00e4nger, aber mit nur 6,9 Millimetern zugleich auch das flachste iPhone aller Zeiten. Und mit nur 129 Gramm angenehm leicht!<\/p>\n<p>&nbsp;<\/p>\n<p>Verbessert hat Apple auch die Verbindungsm\u00f6glichkeiten: Das iPhone 6 unterst\u00fctzt nun <u>stolze 20 LTE B\u00e4nder<\/u>. Das ist kein Schreibfehler und Rekord! Kein anderes Smartphone bietet mehr Kompatibilit\u00e4t und kann praktisch in allen LTE-Netzen der Welt genutzt werden. Mehr dazu im folgenden Abschnitt. Zudem unterst\u00fctzt es LTE der Kategorie 4, so dass iPhone 6 Nutzer prinzipiell mit bis zu 150 MBit\/s mobil surfen k\u00f6nnen. Ein Novum gibt es auch bei den Telefonief\u00e4higkeiten. Zumindest theoretisch <u>beherrscht das neue iPhone auch <a href=\"https:\/\/www.lte-anbieter.info\/volte\/\">Voice over LTE<\/a> (VoLTE)<\/u>, was hierzulande aber noch nicht kommerziell angeboten wird. Wahrscheinlicher Starttermin: Erstes Quartal 2015. Immerhin hat <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\" data-internallinksmanager029f6b8e52c=\"34\" title=\"O2 LTE- und 5G-Tarife zeigen\">O2<\/a> in einigen Gro\u00dfst\u00e4dten VoLTE schon technisch umgesetzt (wir <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/o2-in-grossstaedten-volte-ready\">berichteten<\/a>). Zum Telefonieren m\u00fcsste das Smartphone dann nicht mehr auf das <a href=\"https:\/\/www.lte-anbieter.info\/3g\/\" data-internallinksmanager029f6b8e52c=\"74\" title=\"alles \u00fcber 3G und dessen Abschaltung erfahren\">3G<\/a>-Netz umschalten, was schnelleren Rufaufbau, bessere Sprachqualit\u00e4t und geringeren Stromverbrauch zur Folge h\u00e4tte. LTE CAT6, <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/iphone-6-neue-lte-geruechte\">wie zuvor erhofft<\/a>, unterst\u00fctzen die neuen Modelle allerdings nicht. F\u00fcr Videotelefonie via WLAN gibt es bei Apple das Feature &#8222;Face Time&#8220;; hier wurde beim iPhone 6 auf den WLAN-Standard 802.11 ac aufger\u00fcstet, der bis zu drei Mal schneller laufen soll als beim iPhone 5.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"pic_l_cl\"><img decoding=\"async\" src=\"https:\/\/www.lte-anbieter.info\/lte-news\/wp-content\/uploads\/2014\/09\/iphone6-2.jpg\" alt=\"iphone6 im neuen Gewand\" class=\"fullwidth\"><\/div>\n<p>&nbsp;<\/p>\n<h2>LTE-B\u00e4nder im Einzelnen<\/h2>\n<p>Das iPhone 6 und 6 Plus untersetzten wie schon erw\u00e4hnt 20 LTE-B\u00e4nder. Nutzer sind somit weltweit besser aufgestellt, als mit jedem anderen Smartphone. Im Einzelnen handelt es sich um die B\u00e4nder 1-5, 7,8, 13, 17-20, 25, 26, 28, 29 und 38-41. Die korrespondierenden <a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/frequenzen-lte.php\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Rategeber: alles zum Thema LTE-Frequenzen\">Frequenzen<\/a> k\u00f6nnen Sie hier in <a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/frequenzen-lte.php\">auf dieser Seite<\/a> ermitteln.<\/p>\n<h2>Schnellerer Prozessor und bessere Kamera<\/h2>\n<p>Die Verbindungsm\u00f6glichkeit NFC nutzt Apple, um seinen Bezahldienst Apple Pay einzuf\u00fchren, ein Feature des ebenfalls neuen Betriebssystems iOS 8. So ist der bargeldlose Bezahlvorgang m\u00f6glich, indem man sein iPhone an ein entsprechendes Terminal h\u00e4lt und per Fingerabdruck-Scan bezahlt. Apple Pay startet im Oktober zun\u00e4chst nur in den USA. Welche Partner Apple daf\u00fcr in Deutschland gefunden hat, ist noch nicht bekannt. Noch mehr Leistung verspricht Apples hauseigener <u>neuer 64-Bit-Prozessor A8<\/u>, der vom ebenfalls neuen Grafikchip M8 unterst\u00fctzt wird. Ansonsten hat Apple beim iPhone 6 technisch nur verhalten an der Schraube gedreht. Mit 128 GB gibt es nun eine neue Speichergr\u00f6\u00dfe (neben 16 und 64 GB). Eine Erweiterung per Micro-SD-Karte ist weiterhin nicht m\u00f6glich. <\/p>\n<p>&nbsp;<\/p>\n<p>Die <u>iSight-Kamera<\/u> des iPhone 6 l\u00f6st mit 8 Megapixeln auf, wird begleitet von einer f\/22-Blende und soll dank automatischem Bildstabilisator, verbesserter Gesichtserkennung und Panoramafunktion noch bessere Fotos &#8211; auch im Dunkeln &#8211; erm\u00f6glichen. Hier d\u00fcrfte sich zeigen, dass Megapixel nicht alles sind, schoss doch schon der Vorg\u00e4nger iPhone 5 sehr gute Bilder bei im Vergleich zur Konkurrenz nur m\u00e4\u00dfiger Aufl\u00f6sung. HD-Videos sind mit bis zu 60 Bildern pro Sekunde m\u00f6glich, Zeitlupe gar mit bis zu 240 bps.<\/p>\n<h2>iPhone 6 Plus<\/h2>\n<div class=\"pic_r\"><img decoding=\"async\" src=\"https:\/\/www.lte-anbieter.info\/lte-news\/wp-content\/uploads\/2014\/09\/iphone6-plus.jpg\" alt=\"iphone6 Plus vs. normal\" width=\"290\"><\/div>\n<p>Mit dem iPhone 6 Plus st\u00f6\u00dft Apple nun sogar in die Kategorie der Phablets oder Smartlets vor und duelliert sich hier mit <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/galaxy-note-4-samsungs-neuer-digitaler-notizblock\">Samsungs brandneuem Galaxy Note 4<\/a>, dem <a href=\"https:\/\/www.lte-anbieter.info\/smartphones\/smartphone-lg-g3\">LG G3<\/a> oder dem <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/huawei-ascend-mate-7-lte-cat6-phablet-kommt-zur-ifa\">Huawei Ascend Mate 7<\/a>. Mit der Full-HD-Aufl\u00f6sung seines 5,5 Zoll gro\u00dfen Retina-Displays liegt das iPhone 6 Plus ebenso im Mittelfeld wie mit der Pixeldichte von 401 ppi. Bei der Kamera hat Apple dem iPhone 6 Plus einen optischen Bildstabilisator spendiert, der Verwackler verhindern soll. Ansonsten entspricht das 5,5-Zoll-Modell technisch dem kleineren Bruder.<\/p>\n<p>&nbsp;<\/p>\n<p>Wer \u00fcbrigens Sorgen hat, seine Hand k\u00f6nnte zu klein sein f\u00fcr ein derart gro\u00dfes Display, f\u00fcr den hat Apple den Einhandmodus eingebaut. Durch zweimaliges Dr\u00fccken auf den Homebutton verschiebt sich der Bildschirminhalt nach unten, zum bedienenden Daumen hin. Au\u00dferdem gibt es f\u00fcr den Homescreen jetzt erstmals einen Landscape-Modus, sodass man das Ger\u00e4t auch quer bedienen kann.<\/p>\n<h2>Marktstart und Preise<\/h2>\n<p>Die beiden iPhones k\u00f6nnen in den Farben Gold, Silber oder Grau ab dem kommenden Freitag (12. September) vorbestellt werden und sollen eine Woche sp\u00e4ter, also ab dem 19. September, verf\u00fcgbar sein. In Apple Stores, Apple Online Stores und bei ausgew\u00e4hlten Premium-H\u00e4ndlern kostet das iPhone 6 je nach Speichergr\u00f6\u00dfe 699 (16 GB), 799 (32 GB) oder 899 Euro (128 GB). Das gr\u00f6\u00dfere iPhone 6 Plus wird ohne Vertrag dementsprechend f\u00fcr 799, 899 bzw. 999 Euro angeboten. Hier bei den Mobilfunkbetreibern <a href=\"https:\/\/www.lte-anbieter.info\/details\/magentamobil\" target=\"_blank\" rel=\"nofollow noopener\">Telekom<\/a>, <a href=\"https:\/\/www.lte-anbieter.info\/details\/VFSmart\" target=\"_blank\" rel=\"nofollow noopener\">Vodafone<\/a>, <a href=\"https:\/\/www.lte-anbieter.info\/details\/o2mobil\" target=\"_blank\" rel=\"nofollow noopener\">O2<\/a> und Debitel wird es das neue iPhone auch mit Vertrag geben. <\/p>\n<h2>Fazit: Ist Apple der gro\u00dfe Wurf gelungen?<\/h2>\n<p>Die neuen iPhones werden rei\u00dfenden Absatz finden, daran besteht kein Zweifel. Vor allem optisch sind sie ein Sprung nach vorne: Die Ger\u00e4te sehen nicht nur schick aus und liegen gut in der Hand &#8211; Apple ist endlich \u00fcber seinen Schatten gesprungen und hat an der Displaygr\u00f6\u00dfe geschraubt. Bildschirme um die 5 Zoll haben sich nun mal bei den Nutzern etabliert; es w\u00e4re fahrl\u00e4ssig gewesen, h\u00e4tte sich der Konzern diesem Trend erneut verweigert. Auch NFC hat Apple als letzter gro\u00dfer Hersteller nun integriert. Technisch gab es keine Revolutionen; hier muss man die ersten Tests abwarten, ob die neuen iPhones der Konkurrenz gewachsen &#8211; oder gar \u00fcberlegen &#8211; sind. Kritikw\u00fcrdig ist wie immer die Preisgestaltung, beginnt die Preisspanne doch bei 700 Euro und endet erst bei 1.000. Doch hier gilt auch: Apples iPhone ist eine Marke wie keine andere und hat eine extrem treue Fangemeinde, die nahezu jeden Preis f\u00fcr ein Smartphone aus Cupertino zahlt.<\/p>\n<h3>Wissenswertes zum Thema:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/tarife\/lte-tarifvergleich.php\">Vergleich der LTE Tarife<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/markt-uebersicht-4g.php\">LTE Angebote Markt\u00fcbersicht<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/smartphones\/\">LTE Smartphones im \u00dcberblick<\/a><\/p>\n<div class=\"quellenews2\">\nQuelle und Bilder: Apple\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Eigentlich ist es schade, dass schon im Vorfeld der Apple-Pr\u00e4sentation die wichtigsten Details der neuen iPhones bekannt waren. So blieb der Wow-Effekt, den Steve Jobs einst ausl\u00f6sen konnte, weitestgehend aus. Konzernchef Tim Cook best\u00e4tigte praktisch, was zuvor schon durchgesickert war: Ja, das iPhone 6 wird deutlich gr\u00f6\u00dfer und ja, es kommt in den zwei Gr\u00f6\u00dfen [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":2,"footnotes":""},"categories":[689],"tags":[90,89,332,42],"class_list":["post-14367","post","type-post","status-publish","format-standard","hentry","category-smartphones-2","tag-apple","tag-iphone","tag-lte-smartphone","tag-volte"],"views":4273,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-3JJ","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/14367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=14367"}],"version-history":[{"count":1,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/14367\/revisions"}],"predecessor-version":[{"id":40854,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/14367\/revisions\/40854"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=14367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=14367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=14367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}