{"id":19274,"date":"2015-09-29T17:21:46","date_gmt":"2015-09-29T15:21:46","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=19274"},"modified":"2023-02-20T11:19:12","modified_gmt":"2023-02-20T10:19:12","slug":"o2-volte-fuer-iphone-6s-und-weitere-top-smartphones","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/o2-volte-fuer-iphone-6s-und-weitere-top-smartphones","title":{"rendered":"O2: VoLTE f\u00fcr iPhone 6s und weitere Top-Smartphones"},"content":{"rendered":"<p><a href=\"https:\/\/www.lte-anbieter.info\/volte\/\" data-internallinksmanager029f6b8e52c=\"7\" title=\"mehr \u00fcber VoLTE (LTE-Telefonie) erfahren\">Voice-over-LTE<\/a> ist eine feine Sache &#8211; wenn man es denn mit seinem Smartphone nutzen kann. Viele Modelle sind theoretisch VoLTE-f\u00e4hig, doch um die Telefoniefunktion via LTE auch nutzen zu k\u00f6nnen, muss das Ger\u00e4t vom Provider daf\u00fcr freigeschaltet werden. <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\" data-internallinksmanager029f6b8e52c=\"34\" title=\"O2 LTE- und 5G-Tarife zeigen\">O2<\/a> scheint nun endlich N\u00e4gel mit K\u00f6pfen zu machen: Eine Woche nach dem iPhone 6 und 6 Plus, werden nun auch die neuen Apple-Smartphones iPhone 6s und 6s Plus f\u00fcr VoLTE im O2-Netz freigegeben. Weitere High-End-Smartphones sollen folgen.<!--more--><\/p>\n<h2>VoLTE f\u00fcr iPhone 6s und 6s Plus<\/h2>\n<p>Bislang konnten einzig Besitzer eines Samsung Galaxy S5 und <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/apple-iphone-6-kann-ab-sofort-volte-nutzen\">seit kurzem auch iPhone 6 und 6 Plus<\/a> im O2-Netz via VoLTE telefonieren. Jetzt kommen neue Smartphones hinzu, wobei sich O2-Mutter Telef\u00f3nica Deutschland zun\u00e4chst einmal auf Topmodelle beschr\u00e4nkt. Der Anbieter &#8222;aktiviert zurzeit schrittweise die neuesten LTE-f\u00e4higen Endger\u00e4te f\u00fcr VoLTE&#8220;, wie Telef\u00f3nica auf Anfrage von LTE-Anbieter.info best\u00e4tigte. &#8222;Entsprechend k\u00f6nnen mit dem <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/apple-ios-9-die-neuen-features-im-ueberblick\">Update auf iOS 9<\/a> jetzt auch alle LTE-Vertragskunden von O2 mit einem <a href=\"https:\/\/www.lte-anbieter.info\/smartphones\/smartphone-apple-iphone-6\">iPhone 6, 6 Plus<\/a>, <a href=\"https:\/\/www.lte-anbieter.info\/smartphones\/apple-iphone-6s\">6s und 6s Plus<\/a> VoLTE im Telef\u00f3nica-Netz nutzen.&#8220; Der Provider erkl\u00e4rt auch gleich, was zu tun ist: &#8222;Die Kunden m\u00fcssen dazu nur einmal LTE f\u00fcr &#8218;Sprache &amp; Daten&#8216; in ihren Smartphone-Einstellungen aktivieren und werden dann beim n\u00e4chsten Anruf automatisch f\u00fcr VoLTE freigeschaltet&#8220;, hei\u00dft es.<\/p>\n<h2>Sony, Microsoft und HTC folgen<\/h2>\n<p>Von VoLTE sollen aber nicht nur Apple-Fans profitieren. &#8222;In K\u00fcrze werden dann weitere Ger\u00e4te freigeschaltet, darunter auch das <a href=\"https:\/\/www.lte-anbieter.info\/smartphones\/smartphone-samsung-galaxy-s6\">Samsung Galaxy S6<\/a>, das <a href=\"https:\/\/www.lte-anbieter.info\/smartphones\/sony-xperia-z3\">Sony Xperia Z3 und Z3 Compact<\/a> sowie aktuelle Ger\u00e4te der Hersteller Nokia\/Microsoft und HTC&#8220;, so O2. Sonys neues <a href=\"https:\/\/www.lte-anbieter.info\/smartphones\/smartphone-sony-xperia-z5-premium\">Xperia Z5<\/a> ist zun\u00e4chst nicht dabei; das Topmodell erscheint aber auch erst Ende September. Bei HTC darf man wohl mit dem <a href=\"https:\/\/www.lte-anbieter.info\/smartphones\/smartphone-htc-one-m9\">M9<\/a> rechnen, das schon <a href=\"https:\/\/www.lte-anbieter.info\/lte-advanced\/\">LTE-Advanced<\/a> unterst\u00fctzt.<\/p>\n<h2>Weiter kein VoLTE f\u00fcr Multicards<\/h2>\n<p>Eine Einschr\u00e4nkung gibt es allerdings: &#8222;O2-Multicard-Nutzer k\u00f6nnen VoLTE vorerst nicht nutzen&#8220;, so der Anbieter. &#8222;Wir arbeiten daran und werden wie \u00fcblich zeitnah informieren, sobald das m\u00f6glich ist.&#8220; Schade eigentlich, denn mit einer <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\">O2-Multicard<\/a> kann man drei SIM-Karten &#8211; und damit drei Ger\u00e4te &#8211; mit ein und derselben Mobilnummer nutzen. <\/p>\n<h2>VoLTE bringt viele Vorteile<\/h2>\n<p>O2 hatte <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/o2-startet-voice-over-lte\">im April Voice-over-LTE<\/a> in seinem Netz aktiviert und die <a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/frequenzen-lte.php\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Rategeber: alles zum Thema LTE-Frequenzen\">LTE-Frequenzen<\/a> damit auch f\u00fcr Telefonate freigegeben. <a href=\"https:\/\/www.lte-anbieter.info\/volte\/\">VoLTE<\/a> bringt viele Vorteile: Der Rufaufbau geht schneller vonstatten als im 3G-Netz, die Sprachqualit\u00e4t ist deutlich h\u00f6her (HD-Telefonie) und das Smartphone muss zum Telefonieren nicht st\u00e4ndig vom LTE- ins <a href=\"https:\/\/www.lte-anbieter.info\/3g\/\" data-internallinksmanager029f6b8e52c=\"74\" title=\"alles \u00fcber 3G und dessen Abschaltung erfahren\">UMTS<\/a>-Netz wechseln. Au\u00dferdem senkt VoLTE den Stromverbrauch des Smartphones.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"highlight2\">\nUpdate: Am 11.01.2016 hat auch die Telekom endlich VoLTE eingef\u00fchrt. Mehr dazu <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/telekom-voice-over-lte-volte-endlich-gestartet\">hier<\/a>.\n<\/div>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" width=\"588\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/kd5EBKk0aNw\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/details\/o2start\" target=\"_blank\" rel=\"nofollow noopener\">hier gehts zu O2<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php#smartphone\" target=\"_blank\" rel=\"noopener\">O2 LTE Tarife vergleichen und auch VoLTE nutzen<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/tarife\/lte-tarifvergleich.php\">Vergleich der LTE Tarife<\/a><\/p>\n<div class=\"quellenews2\">Quelle: Telef\u00f3nica Deutschland<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Voice-over-LTE ist eine feine Sache &#8211; wenn man es denn mit seinem Smartphone nutzen kann. Viele Modelle sind theoretisch VoLTE-f\u00e4hig, doch um die Telefoniefunktion via LTE auch nutzen zu k\u00f6nnen, muss das Ger\u00e4t vom Provider daf\u00fcr freigeschaltet werden. O2 scheint nun endlich N\u00e4gel mit K\u00f6pfen zu machen: Eine Woche nach dem iPhone 6 und 6 [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":0,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[689,68,255],"tags":[782,89,48,42,837],"class_list":["post-19274","post","type-post","status-publish","format-standard","hentry","category-smartphones-2","category-lte-anwendungen","category-o2-lte-anbieter","tag-galaxy","tag-iphone","tag-telefonica","tag-volte","tag-xperia"],"views":8007,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":1,"sum_votes":4},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-50S","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/19274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=19274"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/19274\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=19274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=19274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=19274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}