{"id":21731,"date":"2016-06-06T18:15:18","date_gmt":"2016-06-06T16:15:18","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=21731"},"modified":"2021-07-31T11:05:11","modified_gmt":"2021-07-31T09:05:11","slug":"huawei-mediapad-m2-10-und-ipad-pro-97-jetzt-mit-lte-tarifen-bei-11","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/huawei-mediapad-m2-10-und-ipad-pro-97-jetzt-mit-lte-tarifen-bei-11","title":{"rendered":"Huawei MediaPad M2 10 und iPad pro 9,7 jetzt mit LTE Tarifen bei 1&amp;1"},"content":{"rendered":"<p>Mit zwei neuen Tablets will der Anbieter 1&amp;1 aus Montabaur sein Datengesch\u00e4ft ankurbeln. Vermarktet werden zwei Premiumger\u00e4te in Kombination mit den Datentarifen des Anbieters. Doch wie schlagen sich die Angebote und gibt es Kostenfallen?<!--more--><\/p>\n<h2> Zwei Highend Tablets f\u00fcr Liebhaber von Android und iOS <\/h2>\n<p>Das iPad pro 9,7 weist zahlreiche Merkmale auf, welche seinem \u00e4rgsten Konkurrenten aus dem eigenen Hause fehlen: Ein schnellerer Prozessor, ein besserer Bildschirm und eine Ausf\u00fchrung mit 128 GB Speicherplatz kann das iPad Air 2 nicht aufweisen. Ebenso l\u00f6sen beide Kameras mit 12 Megapixel hinten und 5 Megapixel vorne h\u00f6her auf und k\u00f6nnen im Gegensatz zum Air 2 Videos in 4K aufnehmen. Nebenbei weist das iPad pro vier Lautsprecher statt nur zwei auf. Hier sei angemerkt, dass es sich um die Variante handelt, die mit ihrem A9X Prozessor in erster Linie <a href=\"https:\/\/www.lte-anbieter.info\/business\/lte-fuer-firmen.php\" data-internallinksmanager029f6b8e52c=\"64\" title=\"mehr \u00fcber LTE-Tarife f\u00fcr Unternehmen\">Gesch\u00e4ftskunden<\/a> ansprechen soll. Auch drei weitere Merkmale feiern in diesem Modell ihre Premiere: Erstmals ist in einem Apple Tablet ein Blitz f\u00fcr die Kamera hinten und die Apple Sim verbaut. Farblich ist das Tablett im Gegensatz zu den anderen iPads zum ersten Mal auch in der Farbe Rose erh\u00e4ltlich. LTE wird von dem 1&amp;1 vermarkteten iPad pro Modell in \u00fcber 23 B\u00e4ndern unterst\u00fctzt.<\/p>\n<p>&nbsp;<\/p>\n<p>Ebenso ist Huawei mit seinem Tablet MediaPad M2 10 im Segment der hochpreisigen Ger\u00e4te vertreten. Genauso wie bei dem von 1&amp;1 angebotenen Mitbewerbermodell finden Liebhaber von Android beim Huawei Tablet ein schmuckes 10 Zoll Ger\u00e4t im Metallgeh\u00e4use mit Anbindung an das Mobilfunknetz. Auch die Stiftunterst\u00fctzung, die hochaufl\u00f6senden Kameras und die vier vorhandenen Lautsprecher finden sich beim Android Tablet von Huawei wieder. Im Gegensatz zum Apple Tablet wurden hier Lautsprechertechnologie von Harman Kardon verbaut, die f\u00fcr einen besseren Klang sorgen soll. Daf\u00fcr l\u00f6st das verbaute IPS- Display nicht so hoch auf. Statt der RETINA Aufl\u00f6sung des iPads l\u00f6st der Bildschirm &#8222;nur&#8220; mit FULL-HD auf. Der Antrieb ist ein <a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/smartphone\/prozessoren-ueberblick.php\">Octacore-Prozessor<\/a> &#8222;<a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/smartphone\/hisilicon-prozessoren.php\">HiSilicon Kirin 930<\/a>&#8222;, welcher zusammen mit 3 GB Arbeitsspeicher f\u00fcr Leistung sorgt. Der 64 GB interne Speicher kann per MicroSD Karte erweitert werden.<\/p>\n<p>&nbsp;<\/p>\n<p>Die hintere Kamera l\u00f6st mit 13 Megapixeln auf und hat zus\u00e4tzlich einen Bildstabilisator zur Verf\u00fcgung. Jener soll mit der Blenden\u00f6ffnung von F. 2.0 f\u00fcr Fotos in hoher Qualit\u00e4t sorgen. Wie schon das iPad pro hat auch das Huawei einen Fingerabdrucksensor, welcher pers\u00f6nliche Daten sch\u00fctzen soll.<\/p>\n<h2>Premiumger\u00e4t, aber nicht Premiumtarife<\/h2>\n<p>Angeboten werden die beiden Tablets mit den Datentarifen des Anbieters aus Montabaur. Diese weisen neben moderaten Preisen ein in der Branche einmaliges Merkmal auf: W\u00e4hrend der Vertragslaufzeit von 24 Monaten kann man zwischen den beiden angebotenen Netzen wechseln. So kann man flexibel zum besseren Netz wechseln, z.B. wegen eines Umzuges oder Verbesserung der Abdeckung vor Ort. Doch bei aller Flexibilit\u00e4t m\u00fcssen Nutzer aufpassen. W\u00e4hrend die im E-Plus Netz realisierten Tarife nicht nur mit einem reduzierten Grundpreis in den ersten 12 Monaten, sondern auch mit dem Zugang zur 4G-Abdeckung locken, sind die im <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\">Vodafone Netz<\/a> realisierten Angebote unattraktiver. Bei jenen gibt es keine Verg\u00fcnstigung und keinen LTE-Zugang. Hier beschr\u00e4nkt sich die von 1&amp;1 verwendeten Bezeichnung der \u201cbew\u00e4hrten D-Netz Qualit\u00e4t\u201d auf das veraltete <a href=\"https:\/\/www.lte-anbieter.info\/3g\/\" data-internallinksmanager029f6b8e52c=\"74\" title=\"alles \u00fcber 3G und dessen Abschaltung erfahren\">UMTS<\/a> Netz, welches auch heute noch schnelle Datenraten liefert, allerdings mittlerweile weniger Abdeckung als das 4G-Netz bietet.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Internetflats des Angebots kommen in zwei unterschiedlichen Ausf\u00fchrungen. Die Variante mit dem Namen \u201cTablet-Flat L\u201d kommt mit einem Volumen von 2 GB, das Paket mit dem Namen \u201cTablet-XL\u201d bietet 5 GB. Nicht nur die Volumen, sondern auch die Surfgeschwindigkeiten sind unterschiedlich: Im Paket mit dem kleineren Volumen surfen Kunden mit einer Geschwindigkeit von 21,6 Mbit\/s im Download, bei der gr\u00f6\u00dferen Ausf\u00fchrung sind bis zu 42,2 Mbit\/s m\u00f6glich.<\/p>\n<h2>Verf\u00fcgbarkeit und Preise<\/h2>\n<p>Das Huawei MediaPad M2 10  ist mit dem Paket \u201cTablet-Flat XL\u201d mit einem Grundpreis ab 24,99 \u20ac ohne Einmalpreis bestellbar. Niedrigere Grundkosten pro Monat, aber daf\u00fcr ein h\u00f6herer Einmalpreis sind f\u00e4llig, wenn man sich f\u00fcr die \u201cTablet-Flat L\u201d entscheidet. Hier beginnen die Grundpreise ab 16,99 \u20ac. Das Huawei Tablet gibt es f\u00fcr einmalig 249 \u20ac.<\/p>\n<p>&nbsp;<\/p>\n<p>Wer lieber mit Apple Ger\u00e4ten im Internet surft, bekommt das iPad pro f\u00fcr 199,99\u20ac (349 \u20ac f\u00fcr die 128 GB Version) in der Tarifvariante \u201cTablet-Flat XL Premium\u201d mit einem Grundpreis ab 29,99 \u20ac. Alternativ kann man das iOS Ger\u00e4t auch in der normalen \u201cTablet Flat XL\u201d Variante mit einem monatlichen Grundpreis ab 24,99 \u20ac f\u00fcr 349,99 \u20ac (499,99 \u20ac f\u00fcr 128 GB Speicher) einmalig bekommen. Fast 600 \u20ac, beziehungsweise 749 \u20ac f\u00fcr das iPad pro mit 128 GB Speicher, kostet das Tablet, wenn man es in der Variante \u201cTablet-Flat L\u201d mit Grundpreisen ab 16,99 \u20ac bestellt.<br \/>\nDie Tablets und Tarife sind ab sofort <a href=\"https:\/\/www.lte-anbieter.info\/details\/1und1mobil1\" target=\"_blank\" rel=\"nofollow noopener\">hier auf der 1&amp;1 Homepage bestellbar<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&raquo; <a href=\"https:\/\/www.lte-anbieter.info\/lte-hardware\/tests\/16\/huawei-mediapad-m3.php\">Test Huawei Mediapad M3<\/a><\/p>\n<div class=\"quellenews2\">\nQuelle: 1&amp;1\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Mit zwei neuen Tablets will der Anbieter 1&amp;1 aus Montabaur sein Datengesch\u00e4ft ankurbeln. Vermarktet werden zwei Premiumger\u00e4te in Kombination mit den Datentarifen des Anbieters. Doch wie schlagen sich die Angebote und gibt es Kostenfallen?<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":0,"footnotes":""},"categories":[2251,480,956,20,22,253],"tags":[642,2723,2724,2722,8],"class_list":["post-21731","post","type-post","status-publish","format-standard","hentry","category-1und1","category-eplus-lte","category-tablets","category-lte-anbieter","category-lte-sparen","category-vodafone-lte-anbieter","tag-642","tag-2723","tag-huawei-mediapad-m2","tag-ipad-pro-9","tag-lte"],"views":1499,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-5Ev","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/21731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=21731"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/21731\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=21731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=21731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=21731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}