{"id":21868,"date":"2016-06-22T13:25:28","date_gmt":"2016-06-22T11:25:28","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=21868"},"modified":"2016-06-23T13:26:46","modified_gmt":"2016-06-23T11:26:46","slug":"cloud-smartphone-nextbit-robin-kostet-nur-noch-299-dollar","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/cloud-smartphone-nextbit-robin-kostet-nur-noch-299-dollar","title":{"rendered":"Cloud-Smartphone Nextbit Robin kostet nur noch 299 Dollar"},"content":{"rendered":"<p>Ein Vorzeige-Produkt f\u00fcr die vernetzte Generation ist das Smartphone Nextbit Robin, das mit seinen speziell angepassten Cloud-Diensten punktet. Das Mobilger\u00e4t kann auch vom Hersteller nach Deutschland versendet werden \u2013 nun sogar f\u00fcr einen Ger\u00e4tepreis von 299 Dollar (etwa 263 Euro), anstatt wie zuvor 399 Dollar. Gefunkt wird dank des Modems X10 LTE im <a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/smartphone\/snapdragon.php\" data-internallinksmanager029f6b8e52c=\"68\" title=\"alle Snapdragon 4G-Generationen im \u00dcberblick\">Snapdragon<\/a> 808 mit LTE CAT9.<!--more--><\/p>\n<h2>Smartphone mit cleverer Internetnutzung<\/h2>\n<p>Letztes Jahr <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/nextbit-robin-erstes-smartphone-mit-vollintegrierter-cloud\">berichteten<\/a> wir \u00fcber ein besonders spannendes Smartphone, das den Fokus auf eine ausgefeilte Cloud-Anbindung legt, seit Februar 2016 ist das Nextbit Robin nun erh\u00e4ltlich. Den damals ohnehin schon fairen Preis von 399 Dollar hat der Hersteller nun auf 299 Dollar reduziert. Das Highlight an diesem Handy ist die Software, die mit der 100 GB umfassenden Cloud verbunden ist. Das Smartphone merkt sich n\u00e4mlich, wie h\u00e4ufig der Anwender bestimmte Apps oder Mediendateien aufruft. Wenig genutzte Anwendungen oder Bilder werden dann zum Gro\u00dfteil einfach auf den Onlinespeicher hoch- und bei Bedarf wieder heruntergeladen. Das soll automatisch geschehen, sobald der Nutzer mit einem WLAN-Netz und der Steckdose verbunden ist. Bei einem \u00fcppigen LTE-Datentarif kann man sicherlich auch \u00fcber das 4G-Netz die Cloud ansteuern.<\/p>\n<h2>Nextbit Robin: Die technischen Daten<\/h2>\n<p>Mit dem Full-HD-Display (5,2 Zoll) und dem Snapdragon 808 Hexa-Core-Chipsatz samt 3 GB RAM hat das Mobilger\u00e4t eine gute Basis. Wer sich nicht nur auf den Onlinespeicher verlassen m\u00f6chte, kann auch die integrierten 32 GB nutzen. Die LTE-Konnektivit\u00e4t wird mittels des X10-LTE-Modems umgesetzt. Dieses stemmt bis zu <a href=\"https:\/\/www.lte-anbieter.info\/technik\/kategorien-und-3gpp-release.php\">450 Mbit\/s<\/a> im Download und 50 Mbit\/s im Upload. Derzeit bietet aber noch kein Netzbetreiber hierzulande eine solche 4G-Bandbreite beim Downstream an.<\/p>\n<h2>Gefahrloser Versand nach Deutschland<\/h2>\n<p>Das Nextbit Robin l\u00e4sst sich direkt auf der Herstellerseite erstehen und wird auch nach Deutschland verschickt. Versandgeb\u00fchren fallen dabei nicht an. Auch um die <a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/frequenzen-lte.php\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Rategeber: alles zum Thema LTE-Frequenzen\">Frequenzen<\/a> muss man sich keine Gedanken machen, da sogar das wichtige Band 20 (800 Megahertz) im LTE-Netz unterst\u00fctzt wird. Das Robin ist also durchaus eine interessante Alternative zur gro\u00dfen Konkurrenz.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Ein Vorzeige-Produkt f\u00fcr die vernetzte Generation ist das Smartphone Nextbit Robin, das mit seinen speziell angepassten Cloud-Diensten punktet. Das Mobilger\u00e4t kann auch vom Hersteller nach Deutschland versendet werden \u2013 nun sogar f\u00fcr einen Ger\u00e4tepreis von 299 Dollar (etwa 263 Euro), anstatt wie zuvor 399 Dollar. Gefunkt wird dank des Modems X10 LTE im Snapdragon 808 [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":0,"footnotes":""},"categories":[689],"tags":[2744,2063,1894,1561,2252,2743],"class_list":["post-21868","post","type-post","status-publish","format-standard","hentry","category-smartphones-2","tag-299-dollar","tag-android-6-0","tag-hexa-core","tag-lte-cat9","tag-nextbit-robin","tag-preisnachlass"],"views":1062,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-5GI","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/21868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=21868"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/21868\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=21868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=21868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=21868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}