{"id":26614,"date":"2017-12-08T10:52:26","date_gmt":"2017-12-08T09:52:26","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=26614"},"modified":"2017-12-08T10:52:26","modified_gmt":"2017-12-08T09:52:26","slug":"hd-voice-via-lte-nun-netzuebergreifend-bei-telefonica-und-vodafone-moeglich","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/hd-voice-via-lte-nun-netzuebergreifend-bei-telefonica-und-vodafone-moeglich","title":{"rendered":"HD Voice via LTE nun netz\u00fcbergreifend bei Telef\u00f3nica und Vodafone m\u00f6glich"},"content":{"rendered":"<p>HD Voice funktioniert nun auch netz\u00fcbergreifend zwischen Teilnehmer von Telef\u00f3nica (<a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\" data-internallinksmanager029f6b8e52c=\"34\" title=\"O2 LTE- und 5G-Tarife zeigen\">o2<\/a>) und <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\" data-internallinksmanager029f6b8e52c=\"33\" title=\"Vodafone LTE- und 5G-Tarife zeigen\">Vodafone<\/a>. Das teilten die beiden Netzbetreiber via Pressemitteilungen mit. HD Voice gew\u00e4hrt Vorteile wie ein schnellerer Rufaufbau und eine bessere Sprachqualit\u00e4t. Momentan funktioniert die hochqualitative Telefonie zwischen Telef\u00f3nica und Vodafone ausschlie\u00dflich \u00fcber das LTE-Netz.<!--more--><\/p>\n<h2>Mehr Komfort beim Telefonieren<\/h2>\n<p>Im September 2017 fiel die netzinterne Schranke f\u00fcr HD Voice bei <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\">Telef\u00f3nica<\/a> und der Deutschen Telekom. Seitdem k\u00f6nnen die Kunden der beiden Anbieter netz\u00fcbergreifend Unterhaltungen mit verbesserter Gespr\u00e4chsqualit\u00e4t f\u00fchren. Das gilt mittlerweile sowohl f\u00fcr das <a href=\"https:\/\/www.lte-anbieter.info\/3g\/\" data-internallinksmanager029f6b8e52c=\"74\" title=\"alles \u00fcber 3G und dessen Abschaltung erfahren\">3G<\/a>-, wie auch f\u00fcr das 4G-Netz, bei letztgenanntem kommt dann das bew\u00e4hrte <a href=\"https:\/\/www.lte-anbieter.info\/volte\/\">VoLTE<\/a> zum Einsatz. Nutzer eines Tarifs bei <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\">Vodafone<\/a> k\u00f6nnen sich nun ebenfalls \u00fcber ein Plus an Telefonie-Komfort bei Verbindungen zu einem Telef\u00f3nica-Teilnehmer freuen. Auch umgekehrt ist dies der Fall. Telef\u00f3nica verk\u00fcndete, dass HD-Voice-Gespr\u00e4che ab sofort in beiden Richtungen der Netze o2 und Vodafone funktionieren. Die einzigen Voraussetzungen sind, dass die Gespr\u00e4chspartner \u00fcber ein HD-Voice-f\u00e4higes Endger\u00e4t sowie einen LTE-Tarif verf\u00fcgen. Mit netz\u00fcbergreifende HD-Voice-Unterhaltungen \u00fcber 2G und 3G k\u00f6nnen Kunden von Telef\u00f3nica und Vodafone in den kommenden Monaten rechnen.<\/p>\n<h2>\u00dcber HD Voice<\/h2>\n<p>HD Voice \u00fcbermittelt nach dem Voice-over-IP-Konzept die Sprachpakete, was f\u00fcr ein nat\u00fcrlicheres Klangbild und einen schnellen Rufaufbau von nur wenigen Sekunden sorgt. Das WLAN-Netz wird \u00fcbrigens auch nicht au\u00dfer Acht gelassen. VoWiFi, also Voice over WiFi, gew\u00e4hrleistet Telefonate \u00fcber das WLAN \u2013 was nun auch netz\u00fcbergreifend f\u00fcr Telef\u00f3nica und Vodafone gilt.<\/p>\n<h2>EVS soll in Q2 2018 kommen<\/h2>\n<p>\u201eMit der weiteren Zusammenschaltung von HD Voice k\u00f6nnen unsere Kunden nun in alle deutschen Mobilfunknetze mit ausgezeichneter Sprachqualit\u00e4t telefonieren\u201c, freut sich Cayetano Carbajo Mart\u00edn, CTO des M\u00fcnchner Netzbetreibers. Doch Telef\u00f3nica plant schon weitere Optimierungen f\u00fcr die Telefonie. So sei die Einf\u00fchrung des Codecs Enhanced Voice Services (EVS) f\u00fcr das zweite Quartal 2018 geplant. Mit diesem Verfahren verspricht sich das Telekommunikationsunternehmen \u201eeine noch bessere und glasklare Gespr\u00e4chsqualit\u00e4t\u201c.<\/p>\n<h3>Wissenswertes zum Thema:<\/h3>\n<p>\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/tarife\/lte-tarifvergleich.php\">LTE Tarife vergleichen<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/markt-uebersicht-4g.php\">Markt\u00fcbersicht LTE<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/smartphones\/\">LTE Smartphones im \u00dcberblick<\/a><\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>HD Voice funktioniert nun auch netz\u00fcbergreifend zwischen Teilnehmer von Telef\u00f3nica (o2) und Vodafone. Das teilten die beiden Netzbetreiber via Pressemitteilungen mit. HD Voice gew\u00e4hrt Vorteile wie ein schnellerer Rufaufbau und eine bessere Sprachqualit\u00e4t. Momentan funktioniert die hochqualitative Telefonie zwischen Telef\u00f3nica und Vodafone ausschlie\u00dflich \u00fcber das LTE-Netz.<\/p>\n","protected":false},"author":21,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":1,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[20,255,253],"tags":[1086,48,33,42],"class_list":["post-26614","post","type-post","status-publish","format-standard","hentry","category-lte-anbieter","category-o2-lte-anbieter","category-vodafone-lte-anbieter","tag-hd-voice","tag-telefonica","tag-vodafone","tag-volte"],"views":1606,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-6Vg","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/26614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=26614"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/26614\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=26614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=26614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=26614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}