{"id":30446,"date":"2019-07-03T12:04:19","date_gmt":"2019-07-03T10:04:19","guid":{"rendered":"https:\/\/www.lte-anbieter.info\/lte-news\/?p=30446"},"modified":"2019-07-04T08:46:01","modified_gmt":"2019-07-04T06:46:01","slug":"ein-leben-ohne-umts-was-passiert-wenn-der-netzstandard-3g-abgeschaltet-wird","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/ein-leben-ohne-umts-was-passiert-wenn-der-netzstandard-3g-abgeschaltet-wird","title":{"rendered":"Ein Leben ohne UMTS \u2013 Was passiert, wenn der Netzstandard 3G abgeschaltet wird?"},"content":{"rendered":"<p>Mit dem Ende der <a href=\"https:\/\/www.lte-anbieter.info\/5g\/\" data-internallinksmanager029f6b8e52c=\"73\" title=\"alles zum LTE-Nachfolger 5G\">5G<\/a>-Frequenzauktion ist auch ein weiteres Ende wahrscheinlich beschlossene Sache. F\u00fcr mehr Platz f\u00fcr die ultraschnelle Zukunft soll wohl als erstes der 3G-Netzlayer das Feld r\u00e4umen. Doch wann kommt die Abschaltung des 3G-Netzes und was bedeutet es f\u00fcr die Menschen, wenn kein <a href=\"https:\/\/www.lte-anbieter.info\/3g\/\" data-internallinksmanager029f6b8e52c=\"74\" title=\"alles \u00fcber 3G und dessen Abschaltung erfahren\">UMTS<\/a>-Zugang mehr zur Verf\u00fcgung steht?<br \/>\n<!--more--><\/p>\n<h2>Platz f\u00fcr ultraschnelles Internet mit 5G \u2013 UMTS muss weichen<\/h2>\n<p>Nachdem nun die Auktion der Bundesnetzagentur um die begehrten 5G-Breitbandfrequenzen mit 6,55 Milliarden Euro nach \u00fcber 13 Wochen zu Ende ging, soll es losgehen mit dem schnellen Ausbau des ultraschnellen Mobilfunknetzes in Deutschland. Schon weit im Vorfeld der Versteigerung der Frequenzbandpakete \u00e4u\u00dferten sich die Netzbetreiber dazu, wie sie Platz f\u00fcr die neue Generation 5G machen wollen. Einer muss weichen und dies soll 3G, auch bekannt als UMTS, sein. Weil 3G und auch 2G in vielen Landstrichen in Deutschland die einzige Verbindung zur Onlinewelt und ins mobile Netz ist, darf man da ruhig einmal fragen, wann die Abschaltung erfolgen soll und was dies f\u00fcr die Nutzer bedeutet.<\/p>\n<h2>Wann wird UMTS abgeschaltet?<\/h2>\n<p>Die <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/telekom\/telekom-lte.php\">Deutsche Telekom<\/a> wie auch <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\" data-internallinksmanager029f6b8e52c=\"33\" title=\"Vodafone LTE- und 5G-Tarife zeigen\">Vodafone<\/a> sehen UMTS als ersten Layer, den sie abschalten werden. Der technische Leiter von Vodafone Deutschland sieht beispielsweise die Jahre 2020 und 2021 als m\u00f6gliche Termine. Wir werden sehen, ob die Konzerne daran festhalten, denn Fakt ist, dass die Abschaltung wohl einige Funkl\u00f6cher mehr in die deutsche Mobilfunknetzlandschaft rei\u00dfen d\u00fcrfte. So ist auch nicht verwunderlich, dass die Betreiber sich aktuell mit Prognosen zu einem Termin komplett bedeckt halten, ja sogar anders als vor der 5G-Auktion davon sprechen, dass man beides parallel laufen lassen m\u00f6chte.<\/p>\n<h2>Was bedeutet die Abschaltung f\u00fcr die Nutzer der 3G-Frequenzen?<\/h2>\n<p>Rund 30 Prozent der Mobilfunkkunden in Deutschland sind derzeit mit einem Vertrag an das 3G-Netz angebunden. Vor allem Nutzer von alten Vertr\u00e4gen und Discounter-Vertr\u00e4gen w\u00e4ren von einer Abschaltung des UMTS-Standards betroffen. Sie haben keinen Zugriff auf das LTE-Netz der gro\u00dfen Netzanbieter. Zwar gibt es Bekundungen wie zum Beispiel von <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\">Vodafone Deutschland,<\/a> das LTE-Netz auch f\u00fcr diese Kunden zu \u00f6ffnen, doch bisher gilt dies beim Anbieter nur f\u00fcr Neukunden mit neuen Vertr\u00e4gen, beispielsweise bei mobilcom-debitel oder freenetMobile. Eine allgemeine \u00d6ffnung ist bisher noch nicht in Sicht.<\/p>\n<p>&nbsp;<\/p>\n<p>Die <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/telekom\/telekom-lte.php\" data-internallinksmanager029f6b8e52c=\"32\" title=\"LTE- und 5G-Tarife der Deutschen Telekom zeigen\">Deutsche Telekom<\/a> l\u00e4sst ebenfalls nur Kunden mit hochwertigen Vertr\u00e4gen ins LTE-Netz. <a href=\"https:\/\/www.lte-anbieter.info\/prepaid\/prepaid-lte-ratgeber.php\">Prepaidkarten<\/a>-Nutzer k\u00f6nnen generell das 4G-Netz der Telekom nicht nutzen. Jedoch soll bei einer Abschaltung von 3G daf\u00fcr gesorgt werden, dass diese Kunden keine Beeintr\u00e4chtigung erfahren. Darauf muss man auch hoffen, bedenkt man, dass viele Landstriche derzeit selbst wenn das Ger\u00e4t es hergeben w\u00fcrde, nicht in den Genuss des schnelleren Netzes kommen.<\/p>\n<h2>Loch an Loch und h\u00e4lt doch?<\/h2>\n<p>Der schnelle Ausbau des LTE-Netzes inklusive der ultraschnellen 5G-<a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/frequenzen-lte.php\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Rategeber: alles zum Thema LTE-Frequenzen\">Frequenzen<\/a> sollte oberstes Ziel sein, denn wenn kein LTE zur Verf\u00fcgung steht, fallen die Menschen mit nicht kompatiblen Ger\u00e4ten, Vertr\u00e4gen und abgeschiedenen Regionen auf den 2G-Standard zur\u00fcck. Die zweite Generation, auch GSM, deckt zwar nahezu ganz Deutschland ab, ist aber fast nur zum Telefonieren und SMS-Verschicken geeignet. Von einer stabilen und halbwegs schnellen Internetverbindung \u00fcber GSM kann man nur tr\u00e4umen.<\/p>\n<p>&nbsp;<\/p>\n<p>Konzentrieren sich die Netzanbieter nun vor allem auf den Ausbau des LTE-Netzes, wird dies f\u00fcr weite Fl\u00e4chen, die bisher weder UMTS noch LTE nutzen k\u00f6nnen, weiterhin bedeuten, dass sie von einem Funkloch ins n\u00e4chste kommen. Kann man nur hoffen, dass f\u00fcr die Landstriche mit 2G-Standard auch so schnell wie m\u00f6glich eine L\u00f6sung gefunden wird, und die Schere zwischen B\u00fcrgern mit schnellem Internet und denen fast ganz ohne nicht noch gr\u00f6\u00dfer wird.<\/p>\n<p>&nbsp;<\/p>\n<h3>Wissenswertes zum Thema:<\/h3>\n<p><a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/lte-anbieter-uebersicht.php\">LTE-Anbieter in der \u00dcbersicht<\/a><br \/>\n<a href=\"https:\/\/www.lte-anbieter.info\/verfuegbarkeit\/lte-verfuegbarkeit-testen.php\">LTE Verf\u00fcgbarkeit hier testen<\/a><br \/>\n<a href=\"https:\/\/www.lte-anbieter.info\/tarife\/lte-tarifvergleich.php\">LTE Tarife vergleichen<\/a><br \/>\n<a href=\"https:\/\/www.lte-anbieter.info\/markt-uebersicht-4g.php\">Markt\u00fcbersicht LTE<\/a><\/p>\n<div class=\"quellenews2\">Quelle: DNN, Vodafone, Deutsche Telekom<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Mit dem Ende der 5G-Frequenzauktion ist auch ein weiteres Ende wahrscheinlich beschlossene Sache. F\u00fcr mehr Platz f\u00fcr die ultraschnelle Zukunft soll wohl als erstes der 3G-Netzlayer das Feld r\u00e4umen. Doch wann kommt die Abschaltung des 3G-Netzes und was bedeutet es f\u00fcr die Menschen, wenn kein UMTS-Zugang mehr zur Verf\u00fcgung steht?<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":2,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,689,20,21,255,23,254,253],"tags":[14,1082,176,8,96,2646,332,48,27,33],"class_list":["post-30446","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-smartphones-2","category-lte-anbieter","category-lte-ausbau","category-o2-lte-anbieter","category-technik-news","category-telekom-lte-anbieter","category-vodafone-lte-anbieter","tag-4g","tag-5g","tag-deutsche-telekom","tag-lte","tag-lte-auktion","tag-lte-ausbau","tag-lte-smartphone","tag-telefonica","tag-umts","tag-vodafone"],"views":3281,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":5,"sum_votes":23},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-7V4","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/30446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=30446"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/30446\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=30446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=30446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=30446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}