{"id":31709,"date":"2019-12-03T10:52:11","date_gmt":"2019-12-03T09:52:11","guid":{"rendered":"https:\/\/www.lte-anbieter.info\/lte-news\/?p=31709"},"modified":"2019-12-03T10:52:11","modified_gmt":"2019-12-03T09:52:11","slug":"netztest-2019-von-connect","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/netztest-2019-von-connect","title":{"rendered":"Telekom gewinnt auch den Netztest 2019 von connect"},"content":{"rendered":"<p>Das Fachmagazin connect hat zusammen mit Partner umlaut auch in diesem Jahr einen umfangreichen Netztest durchgef\u00fchrt, bei dem Mobilfunknetze und -anbieter in Deutschland, \u00d6sterreich und der Schweiz auf Herz und Nieren gepr\u00fcft wurden. Der deutsche Sieger ist keine sonderlich gro\u00dfe \u00dcberraschung&#8230;<!--more--><\/p>\n<h2>Telekom siegt erneut<\/h2>\n<p>Wie bereits bei den k\u00fcrzlich ver\u00f6ffentlichten Netztest von <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/computer-bild-netztest-deckt-auf-lte-geschwindigkeit-sinkt-im-durchschnitt\">COMPUTER BILD<\/a> sowie <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/chip-netztest-2019\">CHIP<\/a>, hat nun auch connect als drittes gro\u00dfes Fachmagazin in Deutschland seinen Netztest 2019 abgeschlossen und die Ergebnisse ver\u00f6ffentlicht. Wie auch schon bei den anderen beiden Magazinen, gewinnt die <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/telekom\/telekom-lte.php\">Deutsche Telekom<\/a> den Test, erh\u00e4lt zudem als einziger Anbieter das Gesamtergebnis \u201esehr gut\u201c. Damit konnte der Bonner Telekommunikationsanbieter den Vergleich bereits zum neunten Mal in Folge gewinnen.<\/p>\n<p>&nbsp;<\/p>\n<p>Wie auch bei den anderen Netztest belegt <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\">Vodafone<\/a> den zweiten Rang. Der Anbieter konnte, wie auch die Telekom, bei Sprache und Crowdsourcing noch einmal zulegen. Auf dem dritten Platz landet fast schon gewohnt <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\">Telef\u00f3nica\/O2<\/a>. Allerdings belegen die Daten, dass der &#8222;M\u00fcnchner Anbieter beim Zusammenschluss der ehemals getrennten Netze von E-Plus und <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\" data-internallinksmanager029f6b8e52c=\"34\" title=\"O2 LTE- und 5G-Tarife zeigen\">O2<\/a> im letzten Jahr ein gro\u00dfes St\u00fcck vorangekommen ist.&#8220; So konnte Telef\u00f3nica\/O2 den gr\u00f6\u00dften Sprung nach vorne machen.<\/p>\n<p>&nbsp;<\/p>\n<p>Kurz am Rande erw\u00e4hnen wollen wir auch die Ergebnisse aus \u00d6sterreich. Dort konnte sich Magenta (ehemals T-Mobile Austria) erneut den Gesamtsieg mit der Bestnote &#8222;\u00fcberragend&#8220; sichern. Auf den Pl\u00e4tzen folgen A1 Telekom sowie die Hutchison-Marke Drei. In der Schweiz gewinnt die Swisscom hauchd\u00fcnn vor Sunrise sowie Salt.<\/p>\n<h2>Hoher Aufwand f\u00fcr die Testergebnisse<\/h2>\n<p>Zusammen mit Partner &#8222;umlaut&#8220; (ehemals P3 communications), hat connect den Fokus auf die Messung der Leistungsf\u00e4higkeit und Zuverl\u00e4ssigkeit bei Sprache und Daten gelegt. Der Aufwand hierf\u00fcr war wieder sehr hoch. Unter anderem wurden \u00fcber 20.000 km mit Messfahrzeugen zur\u00fcckgelegt und auf fast 400.000 Daten- sowie 50.000 Sprach-Samples zur\u00fcckgegriffen. Zudem wurde das im vergangenen Jahr eingef\u00fchrte Crowdsourcing, bei dem die Ergebnisse der Drive- und Walktests um Langzeitbeobachtungen einer gro\u00dfen Zahl von Mobilfunknutzern erg\u00e4nzt werden weiter verfeinert. Zudem haben die Tester beim aktuellen Netztest 2019 sogar schon erste Messungen f\u00fcr <a href=\"https:\/\/www.lte-anbieter.info\/5g\/\">5G<\/a> durchgef\u00fchrt.<\/p>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Das Fachmagazin connect hat zusammen mit Partner umlaut auch in diesem Jahr einen umfangreichen Netztest durchgef\u00fchrt, bei dem Mobilfunknetze und -anbieter in Deutschland, \u00d6sterreich und der Schweiz auf Herz und Nieren gepr\u00fcft wurden. Der deutsche Sieger ist keine sonderlich gro\u00dfe \u00dcberraschung&#8230;<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":0,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[66],"tags":[3545,942,176,267,943,138,48,33],"class_list":["post-31709","post","type-post","status-publish","format-standard","hentry","category-studien-prognosen","tag-3545","tag-connect","tag-deutsche-telekom","tag-deutschland","tag-netztest","tag-o2","tag-telefonica","tag-vodafone"],"views":3974,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":3,"sum_votes":9},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-8fr","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/31709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=31709"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/31709\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=31709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=31709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=31709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}