{"id":33294,"date":"2020-06-26T17:11:36","date_gmt":"2020-06-26T15:11:36","guid":{"rendered":"https:\/\/www.lte-anbieter.info\/lte-news\/?p=33294"},"modified":"2020-07-10T14:01:54","modified_gmt":"2020-07-10T12:01:54","slug":"telefonica-scheitert-wieder-bei-versorgungsauflagen","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/telefonica-scheitert-wieder-bei-versorgungsauflagen","title":{"rendered":"Telef\u00f3nica scheitert wieder bei Versorgungsauflagen"},"content":{"rendered":"<p>Anfang des Jahres wurde bekannt, dass die Telef\u00f3nica Deutschland die Auflagen der Bundesnetzagentur f\u00fcr Ende 2019 deutlich verfehlt hat. Auch Ende Juni mit dem n\u00e4chsten Etappenziel sieht es nicht viel besser aus.<!--more--><\/p>\n<h2>Auflagen wieder verpasst<\/h2>\n<p><a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/bundesnetzagentur-telefonica-verpasst-versorgungsauflagen-deutlich\">Im Januar war bekannt geworden<\/a>, dass <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\">Telef\u00f3nica Deutschland<\/a> als einziger der drei Netzbetreiber die Versorgungsauflagen der Bundesnetzagentur ziemlich deutlich verpasst hat. Die f\u00fcr Ende 2019 vorgegebenen Ziele wurden zum Teil recht weit verfehlt.<\/p>\n<p>&nbsp;<\/p>\n<p>Auch 2020 geht es nicht viel besser weiter. Denn der Anbieter wird auch den f\u00fcr  Ende Juni vorgeschriebenen <a href=\"https:\/\/www.lte-anbieter.info\/verfuegbarkeit\/netzausbau-abdeckung-lte.php\">LTE-Ausbau<\/a> um 3.040 neue Standorte nicht schaffen. Dies hat das Unternehmen in einem Brief an den Beirat der Bundesnetzagentur offenbart, wie die Rheinische Post berichtet. Dennoch bittet Telef\u00f3nica Deutschland die Bundesnetzagentur darum, von dem angedrohten Zwangsgeld verschont zu bleiben.<\/p>\n<h2>Corona als Grund?<\/h2>\n<p>Im Zeitraum von Januar bis Ende Juni hat Telef\u00f3nica Deutschland 2.005 neue Stationen f\u00fcr LTE in ganz Deutschland in Betrieb genommen. 1.151 weitere Stationen sind hingegen noch nicht so weit. Als Grund gibt der Konzern hier die Corona-Krise an, die aufgrund von fehlenden Bauteilen wohl f\u00fcr Verz\u00f6gerungen gesorgt hat. Im gleichen Atemzug versichert das Unternehmen, dass die noch ausstehenden Sender bis Ende Juli in Betrieb genommen werden sollen. Gegen\u00fcber Golem hat der Telef\u00f3nica-Sprecher Klaus Schulze-L\u00f6wenberg verk\u00fcndet, dass bis Jahresende insgesamt 7.600 LTE-Stationen umger\u00fcstet oder neu gebaut werden sollen. <\/p>\n<p>&nbsp;<\/p>\n<p>Grund f\u00fcr den Stress mit der Bundesnetzagentur sind Auflagen, die bei der Zuteilung der im Jahr 2015 versteigerten <a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/frequenzen-lte.php\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Rategeber: alles zum Thema LTE-Frequenzen\">Frequenzen<\/a> gemacht wurden. Hier wurde angeordnet, dass ab Beginn 2020 98 Prozent der Haushalte bundesweit und 97 Prozent der Haushalte in jedem Bundesland mit einer Mindestgeschwindigkeit von 50 MBit\/s zu versorgen sind. Zudem m\u00fcssen alle Hauptverkehrswege vollst\u00e4ndig versorgt sein. Alle drei Mobilfunknetzbetreiber verpassten die Ziele mehr oder weniger knapp und erhielten deshalb eine Frist zur Nachbesserung der verfehlten Versorgungsauflagen, wie die Bundesnetzagentur im Fr\u00fchjahr erkl\u00e4rte.<\/p>\n<h2>Update 09.07.2020<\/h2>\n<p>Nachdem Telef\u00f3nica die LTE-Ausbauauflagen erneut verfehlte, hat die Bundesnetzagentur dem Netzbetreiber eine Fristverl\u00e4ngerung bis Ende Juli gew\u00e4hrt. Sollten die Ziele dann immer noch nicht erf\u00fcllt sein, droht ein Zwangsgeld in H\u00f6he von 600.000 Euro. Dies hat die Regulierungsbeh\u00f6rde am heutigen Donnerstag bekanntgegeben.<\/p>\n<div class=\"quellenews2\">\nQuelle: Rheinische Post \/ Golem \/ Telef\u00f3nica Deutschland\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Anfang des Jahres wurde bekannt, dass die Telef\u00f3nica Deutschland die Auflagen der Bundesnetzagentur f\u00fcr Ende 2019 deutlich verfehlt hat. Auch Ende Juni mit dem n\u00e4chsten Etappenziel sieht es nicht viel besser aus.<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":0,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,20,21,255],"tags":[136,2646,1781],"class_list":["post-33294","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-lte-anbieter","category-lte-ausbau","category-o2-lte-anbieter","tag-bundesnetzagentur","tag-lte-ausbau","tag-telefonica-deutschland"],"views":1301,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-8F0","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/33294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=33294"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/33294\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=33294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=33294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=33294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}