{"id":3463,"date":"2011-02-28T19:19:46","date_gmt":"2011-02-28T18:19:46","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=3463"},"modified":"2023-02-22T11:46:16","modified_gmt":"2023-02-22T10:46:16","slug":"koeln-erste-stadt-mit-lte","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/koeln-erste-stadt-mit-lte","title":{"rendered":"K\u00f6ln wird erste Stadt mit LTE"},"content":{"rendered":"<p>Wenn es um den LTE Ausbau geht, steht bisher der l\u00e4ndliche Raum im Fokus. Gro\u00dfst\u00e4dte d\u00fcrfen von den Netzbetreibern erst unter gewissen Voraussetzungen erschlossen werden. Die Telekom hat nun bekannt gegeben, dass in K\u00f6ln, als erste Stadt, LTE verf\u00fcgbar gemacht wird.<!--more--><\/p>\n<h2>Erst die wei\u00dfen Flecken\u2026<\/h2>\n<p>Die <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/telekom\/telekom-lte.php\">Telekom<\/a>, <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\">Vodafone<\/a> und <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\">O2<\/a> haben im Zuge der Ersteigerung der <a href=\"https:\/\/www.lte-anbieter.info\/ratgeber\/frequenzen-lte.php\" data-internallinksmanager029f6b8e52c=\"8\" title=\"Rategeber: alles zum Thema LTE-Frequenzen\">LTE-Frequenzen<\/a> im Spektrum der <a href=\"https:\/\/www.lte-anbieter.info\/digitale_dividende.php\">Digitalen Dividende<\/a> Auflagen unterwerfen m\u00fcssen. Diese verpflichten, <a href=\"https:\/\/www.lte-anbieter.info\">LTE<\/a> sukzessive erst in den Gebieten aufzubauen, die bislang nicht mit DSL versorgt sind. Erst wenn ein Gro\u00dfteil der nach Priorit\u00e4tsstufen gegliederten Regionen ausgebaut sind, geht es an die lukrativen Metropolen. Denn dort warten die meisten Kunden auf superschnelles LTE-Internet f\u00fcr unterwegs. Auf dieser <a href=\"https:\/\/www.lte-anbieter.info\/verfuegbarkeit\/netzausbau-abdeckung-lte.php\">Karte<\/a> erfahren Sie mehr zum Netzausbau und k\u00f6nnen Orte nach Priorit\u00e4tsstufe anzeigen lassen.<\/p>\n<h2>K\u00f6ln \u201eLTE City\u201c<\/h2>\n<p>Als erstes k\u00f6nnen sich die K\u00f6lner auf mobiles Highspeed-Internet freuen. Hier plant die <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/telekom\/telekom-lte.php\" data-internallinksmanager029f6b8e52c=\"32\" title=\"LTE- und 5G-Tarife der Deutschen Telekom zeigen\">Deutsche Telekom<\/a> im Sommer die Premiere f\u00fcr das neue Breitband-Mobilfunknetz der 4. Generation im urbanen Bereich. Welche Metropolen als n\u00e4chstes folgen, ist leider noch nicht bekannt. Wahrscheinlich wird es aber anschlie\u00dfen recht schnell gehen.<\/p>\n<h2>Tests laufen bald an<\/h2>\n<div class=\"pic_l\"><img decoding=\"async\" src=\"https:\/\/www.lte-anbieter.info\/lte-news\/wp-content\/uploads\/2011\/02\/surfen-per-lte.jpg\" alt=\"Surfen per LTE von der Telekom\" title=\"Surfen per LTE von der Telekom\" width=\"300\"><\/div>\n<p>In der Stadt verspricht LTE, im Gegensatz um Land, weit mehr Leistung. Downloadraten von bis zu 100 MBit\/s gelten als m\u00f6glich. Die Telekom m\u00f6chte im Fr\u00fchsommer ersten <a href=\"https:\/\/www.lte-anbieter.info\/business\/lte-fuer-firmen.php\" data-internallinksmanager029f6b8e52c=\"64\" title=\"mehr \u00fcber LTE-Tarife f\u00fcr Unternehmen\">Gesch\u00e4ftskunden<\/a> LTE anbieten. Und zwar \u00fcber einen \u201eFriendly User Test\u201c. Auch <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\" data-internallinksmanager029f6b8e52c=\"34\" title=\"O2 LTE- und 5G-Tarife zeigen\">O2<\/a> hat bereits einen solchen absolviert. Bei einem \u201eFriendly User Test\u201c, werden kurz vor dem offiziellen Marktstart einige ausgew\u00e4hlte Kunden zu einem kostenlosen Praxistest eingeladen, der meist \u00fcber einige Wochen geht. Die gewonnenen Informationen, \u00fcber etwaige Probleme oder Verbesserungen, gehen dann in die finale Produktoptimierung ein. Anschlie\u00dfend soll LTE breitfl\u00e4chig und nat\u00fcrlich auch f\u00fcr Privatkunden angeboten werden.  LTE wird von der Telekom auf den Frequenzen 1.8 und 2.6 GHz betrieben. Die <a href=\"https:\/\/www.lte-anbieter.info\/lte-hardware\/sticks\/lte-stick-uebersicht.php\">LTE-Sticks<\/a> (bei der Telekom von Huawei) m\u00fcssen also diese B\u00e4nder unterst\u00fctzen. Auf dem Land wird LTE bekanntlich auf einem Band um 800 MHz eingesetzt.<\/p>\n<h3>Wissenswertes zum Thema:<\/h3>\n<p>&raquo; <a href=\"https:\/\/www.lte-anbieter.info\/details\/TelekomLTE\" target=\"_blank\" rel=\"nofollow noopener\">direkt zu Telekom LTE<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/telekom\/telekom-lte.php\">LTE Tarife von der Telekom<\/a><\/p>\n<div class=\"quellenews2\">\nQuelle + Bild: Deutsche Telekom Presse\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Wenn es um den LTE Ausbau geht, steht bisher der l\u00e4ndliche Raum im Fokus. Gro\u00dfst\u00e4dte d\u00fcrfen von den Netzbetreibern erst unter gewissen Voraussetzungen erschlossen werden. Die Telekom hat nun bekannt gegeben, dass in K\u00f6ln, als erste Stadt, LTE verf\u00fcgbar gemacht wird.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":5,"footnotes":""},"categories":[20,21,254],"tags":[504,8,505],"class_list":["post-3463","post","type-post","status-publish","format-standard","hentry","category-lte-anbieter","category-lte-ausbau","category-telekom-lte-anbieter","tag-koln","tag-lte","tag-stadt"],"views":3665,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-TR","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/3463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=3463"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/3463\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=3463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=3463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=3463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}