{"id":4383,"date":"2011-06-28T14:26:33","date_gmt":"2011-06-28T12:26:33","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=4383"},"modified":"2023-02-22T11:41:36","modified_gmt":"2023-02-22T10:41:36","slug":"startet-o2-lte-doch-ohne-fritzbox","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/startet-o2-lte-doch-ohne-fritzbox","title":{"rendered":"Startet O2 die LTE-Tarife doch ohne Fritz!Box?"},"content":{"rendered":"<p>In wenigen Tagen ist es soweit. <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/o2\/o2-lte.php\" data-internallinksmanager029f6b8e52c=\"34\" title=\"O2 LTE- und 5G-Tarife zeigen\">O2<\/a> startet offiziell ins LTE-Zeitalter. Zuvor gab es Anlass zur Spekulation, dass die Angebote zusammen mit der hei\u00df ersehnten Fritz!Box 6840 f\u00fcr LTE erh\u00e4ltlich sein werden. Es gibt jedoch drei Indizien, die leider dagegen sprechen.<!--more--><\/p>\n<h2>Long Term Evolution Internet von O2<\/h2>\n<p>Das dritte Unternehmen in Deutschland wird in 3 Tagen, am 01. Juli, die <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/o2-lte-fuer-zuhause\">Vermarktung f\u00fcr LTE-Internet starten<\/a>. Allerdings ist die \u201eO2 Telef\u00f3nica Germany\u201c gewisserma\u00dfen schon ein Nachz\u00fcgler. Denn <a href=\"https:\/\/www.lte-anbieter.info\/lte-provider\/vodafone\/vodafone-lte.php\" data-internallinksmanager029f6b8e52c=\"33\" title=\"Vodafone LTE- und 5G-Tarife zeigen\">Vodafone<\/a> hat die schnelle DSL-Alternative schon seit Ende 2010 im Angebot. Die Telekom startete exakt <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/telekom-startet-lte-verkauf\">3 Monate zuvor<\/a>. <\/p>\n<h2>O2 LTE samt Fritz!Box?<\/h2>\n<div class=\"pic_l\"><img decoding=\"async\" src=\"https:\/\/www.lte-anbieter.info\/lte-news\/wp-content\/uploads\/2011\/06\/fritzbox-6840.jpg\" alt=\"Fritz!Box 6840 von AVM - Router speziell f\u00fcr LTE\" title=\"Fritz!Box 6840 von AVM - Router speziell f\u00fcr LTE\" width=\"290\"><\/p>\n<p>Hei\u00df ersehnt: Die erste Frit!Box speziell f\u00fcr LTE-Internet<\/p>\n<\/div>\n<p>Bislang sind Router und Sticks f\u00fcr LTE noch rar auf dem Markt. Nur wenige Hersteller haben aktuell <a href=\"https:\/\/www.lte-anbieter.info\/lte-hardware\/all\/\">Ger\u00e4te<\/a> im Angebot. Zudem gibt es mit dem ein oder anderen noch technische Probleme. Daher erwarten viele LTE-User, oder solche, die es bald werden wollen, die <a href=\"https:\/\/www.lte-anbieter.info\/lte-hardware\/all\/router-avm-fritzbox-6840-lte\">Fritz!Box 6840 von AVM<\/a>. Diese ist speziell f\u00fcr die 4G-Funktechnik konzipiert und bietet, wie f\u00fcr AVM \u00fcblich, geballte Leistung, hervorragenden Support und alle modernen Features, die ein Router haben sollte. Noch ist die LTE-FritzBox leider nicht erh\u00e4ltlich. In einem <a href=\"https:\/\/www.lte-anbieter.info\/interviews\/11\/schoellhammer.php\">Interview erfuhren wir j\u00fcngst<\/a>, dass es noch im 2. Quartal soweit sein soll. Damit fiele der letztm\u00f6gliche Termin auf einen Tag vor dem O2-LTE-Verkaufsstart. Zufall? Es gab allerdings noch weitere Indizien daf\u00fcr, dass zumindest O2 den Router f\u00fcr Neukunden anbieten wird. Denn im Zuge der zuvor laufenden <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/o2-nutzer-lte-halbes-jahr-kostenlos\">LTE-Friendly-Usertests<\/a>, wurden die Ger\u00e4te in einer Kooperation an einzelne Testkunden geliefert.<\/p>\n<p>&nbsp;<\/p>\n<p>Was spricht nun gegen die These? Die eigens eingerichtete Infoseite auf <a href=\"https:\/\/www.o2online.de\" target=\"_blank\" rel=\"noopener\">www.o2online.de<\/a>, enth\u00e4lt einen FAQ-Bereich. Unter dem Punkt \u201eWie gro\u00df ist die WLAN-Reichweite des LTE-Routers?\u201c, findet sich ein Hinweis, der gegen die Fritz!Box spricht. Die WLAN-Reichweite entspr\u00e4che dem des WLAN-Standards IEEE 802.11b\/g. Der Knackpunkt ist aber: Die Fritz!Box 8640 unterst\u00fctzt den neuesten \u201eN\u201c-Standard. Also <a href=\"https:\/\/www.lte-anbieter.info\/technik\/wlan\/wlan-ratgeber.php\" target=\"_blank\" rel=\"noopener\">IEEE 802.11n<\/a>. Dieser zeichnet sich unter anderem durch eine h\u00f6here Reichweite aus und unterst\u00fctzt MIMO 2&#215;2. Eine Mehrantennentechnik zur Empfangsverbesserung des heimischen WLAN-Netzes. Und noch ein drittes Indiz: Die Angebote, die O2 im Juli ins Rennen schickt, sind zun\u00e4chst reine Surftarife ohne Telefonie. Eine Fritz!Box w\u00e4re daf\u00fcr vollkommen \u00fcberdimensioniert. Denn das Ger\u00e4t ist gleichzeitig eine moderne Telefonanlage samt digitalem Anrufbeantworter.<\/p>\n<h2>Fazit<\/h2>\n<p>Das hei\u00dft nicht, dass O2 die Fritz!box als 2. Wahlrouter anbieten wird. Der Standard-Router wird es demnach unserer Meinung nach aber nicht. Am 01.07. werden wir es genau wissen \u2026<\/p>\n<h2>Update:<\/h2>\n<p>Heute <a href=\"https:\/\/www.lte-anbieter.info\/lte-news\/jetzt-verfuegbar-o2-lte-startet\">startete O2 offiziell<\/a> den Verkauf der LTE-Angebote. Wie erwartet von der FritzBox bisher keine Spur. Statt dessen gibt es den Huawei 398. Der Preis betr\u00e4gt einmalig 49.90 \u20ac. Ohne Vertrag verlangt O2 stolze 339 \u20ac f\u00fcr den <a href=\"https:\/\/www.lte-anbieter.info\/lte-hardware\/router\/lte-router-ratgeber.php\" data-internallinksmanager029f6b8e52c=\"23\" title=\"LTE Router in der \u00dcbersicht + Ratgeber\">LTE-Router<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"quellenews2\">\nBild: AVM Presse\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>In wenigen Tagen ist es soweit. O2 startet offiziell ins LTE-Zeitalter. Zuvor gab es Anlass zur Spekulation, dass die Angebote zusammen mit der hei\u00df ersehnten Fritz!Box 6840 f\u00fcr LTE erh\u00e4ltlich sein werden. Es gibt jedoch drei Indizien, die leider dagegen sprechen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":1,"footnotes":""},"categories":[72,20,255],"tags":[424,8,138],"class_list":["post-4383","post","type-post","status-publish","format-standard","hentry","category-lte-hardware","category-lte-anbieter","category-o2-lte-anbieter","tag-fritzbox","tag-lte","tag-o2"],"views":1999,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-18H","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/4383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=4383"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/4383\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=4383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=4383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=4383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}