{"id":97,"date":"2009-01-15T11:30:37","date_gmt":"2009-01-15T10:30:37","guid":{"rendered":"http:\/\/www.lte-anbieter.info\/lte-news\/?p=97"},"modified":"2011-03-12T10:16:06","modified_gmt":"2011-03-12T09:16:06","slug":"kommerzielles-lte-mobilfunknetz-von-teliasonera-und-ericsson","status":"publish","type":"post","link":"https:\/\/www.lte-anbieter.info\/lte-news\/kommerzielles-lte-mobilfunknetz-von-teliasonera-und-ericsson","title":{"rendered":"Kommerzielles LTE-Mobilfunknetz von TeliaSonera und Ericsson"},"content":{"rendered":"<p>Das schwedische Unternehmen Ericsson und der Kommunikationskonzern TeliaSonera gaben heute die Unterzeichnung eines gemeinsamen Vertrages bekannt, laut dem beide ein kommerzielles LTE-Mobilfunknetz in Stockholm aufbauen m\u00f6chten. Dieses Netz soll ein Mobil-Breitbandnetz der Superlative werden. Lesen Sie hier mehr.<!--more--><\/p>\n<h2>Kommerzielle Einf\u00fchrung bis 2010 geplant<\/h2>\n<p>Der Bau des Netzes hat bereits unter Verantwortung von Ericsson begonnen und soll bis 2010 abgeschlossen sein. 2010 wird dann auch laut Plan die kommerzielle Inbetriebnahme erfolgen. Zu beginn soll Ericsson den Betrieb des Netzes \u00fcbernehmen. Doch laut der Vereinbarung mit TeliaSonera m\u00f6chten beide Unternehmen eine langfristige Partnerschaft aufbauen, bei der auch die Nutzung von mobilen LTE-Breitbanddiensten f\u00fcr Verbraucher weiterentwickelt werden soll.<\/p>\n<h2>Einf\u00fchrung von 4G im Breitbandbereich hat hohe Bedeutung<\/h2>\n<p>Mit der Inbetriebnahme des neuen Mobil-Breitbandnetzes der so genannten vierten Generation (4G) wird die h\u00f6chste mobile Datenrate, die jemals erzielt wurde noch um einiges \u00fcbertroffen. Rund zehn mal h\u00f6here Geschwindigkeiten als bei aktuellen Netzen sind m\u00f6glich. 4G bietet au\u00dferdem eine viel bessere Interaktivit\u00e4t und Qualit\u00e4t. Echtzeit-Anwendungen werden erm\u00f6glicht und Nutzer k\u00f6nnen auch unterwegs immer online sein. Dadurch kann auch eine Vielzahl neuer Dienste realisiert werden. Aus diesen Gr\u00fcnden wird der Einf\u00fchrung von 4G im Breitbandbereich dieselbe Bedeutung wie der Einf\u00fchrung der Mobiltelefonie im Sprachbereich zugemessen.<\/p>\n<h2>Beide Beteiligten loben Partnerschaft<\/h2>\n<p>Beide Partner \u00e4u\u00dferten sich begeistert \u00fcber den Vertrag. Erik Hallberg, Senior Vice President und Leiter von Mobility Services Sweden von TeliaSonera sagt: &#8222;Unsere Kunden z\u00e4hlen zu den weltweit fortschrittlichsten Nutzern von Telekommunikationsdiensten. Mit 4G werden wir ihnen die besten derzeit realisierbaren mobilen Breitbandleistungen bieten k\u00f6nnen. Wir haben uns dabei f\u00fcr Ericsson als Partner entschieden. Diese Entscheidung haben wir nicht nur wegen der beeindruckenden Erfolgsgeschichte von Ericsson im Bereich mobiler Technologien getroffen. Entscheidend war auch, dass Ericsson bereits fr\u00fch auf die Entwicklung der LTE-Technologie und auf die Bereitstellung entsprechender Ressourcen f\u00fcr deren technische Einf\u00fchrung gesetzt hat.&#8220;<\/p>\n<p>&nbsp;<\/p>\n<p>Mikael B\u00e4ckstr\u00f6m, President bei Ericsson f\u00fcr Skandinavien und das Baltikum erg\u00e4nzt: &#8222;Wir sind sehr gl\u00fccklich, unsere Partnerschaft mit TeliaSonera fortzusetzen. Diese Zusammenarbeit markiert einen wichtigen Meilenstein. Mit LTE lassen sich Netze gr\u00f6\u00dftm\u00f6glicher Leistungsf\u00e4higkeit und Kapazit\u00e4t aufbauen. So k\u00f6nnen die Anforderungen, die die schnell wachsende Zahl von mobilen Breitbandnutzern auf der ganzen Welt stellt, erf\u00fcllt werden.&#8220;<\/p>\n<h2>Weiterf\u00fchrendes<\/h2>\n<p>\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/verfuegbarkeit\/lte-karte.php\">LTE Karte<\/a><br \/>\n\u00bb <a href=\"https:\/\/www.lte-anbieter.info\/lte-anwendungen.php\">zuk\u00fcnftige Anwendungen f\u00fcr LTE<\/a><\/p>\n<div class=\"quellenews2\">\nQuelle: www.ericsson.com Presse\n<\/div>\n<div style='text-align:center' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Das schwedische Unternehmen Ericsson und der Kommunikationskonzern TeliaSonera gaben heute die Unterzeichnung eines gemeinsamen Vertrages bekannt, laut dem beide ein kommerzielles LTE-Mobilfunknetz in Stockholm aufbauen m\u00f6chten. Dieses Netz soll ein Mobil-Breitbandnetz der Superlative werden. Lesen Sie hier mehr.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","iawp_total_views":2,"footnotes":""},"categories":[1,21],"tags":[14,3,8,13],"class_list":["post-97","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-lte-ausbau","tag-4g","tag-ericsson","tag-lte","tag-teliasonera"],"views":2459,"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOOxv-1z","_links":{"self":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/comments?post=97"}],"version-history":[{"count":0,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/posts\/97\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/media?parent=97"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/categories?post=97"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lte-anbieter.info\/lte-news\/wp-json\/wp\/v2\/tags?post=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}